{"id":14219,"date":"2022-09-01T14:08:17","date_gmt":"2022-09-01T14:08:17","guid":{"rendered":"https:\/\/bluetab.net\/?p=14219"},"modified":"2022-09-01T14:08:17","modified_gmt":"2022-09-01T14:08:17","slug":"gobierno-del-dato-en-el-sector-de-los-servicios-de-contact-center","status":"publish","type":"post","link":"https:\/\/bluetab.co.uk\/en\/2022\/09\/gobierno-del-dato-en-el-sector-de-los-servicios-de-contact-center\/","title":{"rendered":"Gobierno del dato en el sector de los servicios de Contact Center"},"content":{"rendered":"<h1>Gobierno del dato en el sector de los servicios de Contact Center<\/h1>\n<figure><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/bluetab.net\/wp-content\/uploads\/2022\/03\/Isotipo-Bluetab-150x150.png\" alt=\"\" loading=\"lazy\"><\/figure>\n<h4>Bluetab<\/h4>\n<p>Nuestro cliente es una compa\u00f1\u00eda multinacional de origen franc\u00e9s, con m\u00e1s de 44 a\u00f1os de experiencia en <strong>servicios de Contact Center&nbsp;<\/strong>(Business Process Outsourcing o BPO). Con m\u00e1s de 380 Mil empleados, y trabajando en m\u00e1s de 170 pa\u00edses y 260 lenguas.<\/p>\n<p>El sector de los servicios de Contact Center es un mercado en continua transformaci\u00f3n con unas expectativas de crecimiento, seg\u00fan la generalidad de los analistas, por encima del 13-15%. Y que est\u00e1 experimentando dos grandes tendencias: el incre\u00edble <strong>crecimiento de las plataformas de datos de cliente<\/strong> y la <strong>aplicaci\u00f3n de la inteligencia artificial en servicios omnicanal de atenci\u00f3n al cliente<\/strong>.<\/p>\n<p>En esa coyuntura, nuestro cliente est\u00e1 transformando sus capacidades para asegurar que la <strong>explotaci\u00f3n de sus datos<\/strong> sea eficiente y pueda <strong>ofrecer valores diferenciales a sus clientes<\/strong>. Y, para ello, la definici\u00f3n de pol\u00edticas y de un modelo de gobierno de datos adaptados a sus necesidades es hoy cr\u00edtico.<\/p>\n<p>Bluetab tiene una amplia experiencia en <strong>proyectos de implantaci\u00f3n de pol\u00edticas y modelos de gobierno de datos<\/strong>, por lo que aplicando las buenas pr\u00e1cticas logr\u00f3 definir para el cliente un plan de 12 semanas de trabajo que asegur\u00f3 el establecimiento de las bases fundamentales de dichas pol\u00edticas de gobierno, y la implantaci\u00f3n de una herramienta como <a href=\"https:\/\/www.truedat.io\/\">Truedat<\/a>, que asegura el soporte de la gesti\u00f3n automatizada de la implantaci\u00f3n del modelo de gobierno.<\/p>\n<p>De esta forma, nuestro cliente ha realizado la puesta en marcha de su primer caso de uso <em>end-to-end<\/em>, lo que le ha permitido, adem\u00e1s de mostrar a negocio de forma tangible el valor del proyecto y lograr definir roles y responsabilidades para la gesti\u00f3n de los datos, estar preparado para el despliegue incremental y controlado de otros casos de uso en su ecosistema con sus capacidades y sin depender de terceros si no lo estima adecuado.<\/p>\n<p><img decoding=\"async\" width=\"1024\" height=\"548\" src=\"https:\/\/bluetab.net\/wp-content\/uploads\/2022\/09\/piezas-1024x548.png\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/bluetab.net\/wp-content\/uploads\/2022\/09\/piezas-1024x548.png 1024w, https:\/\/bluetab.net\/wp-content\/uploads\/2022\/09\/piezas-300x161.png 300w, https:\/\/bluetab.net\/wp-content\/uploads\/2022\/09\/piezas-768x411.png 768w, https:\/\/bluetab.net\/wp-content\/uploads\/2022\/09\/piezas-1536x823.png 1536w, https:\/\/bluetab.net\/wp-content\/uploads\/2022\/09\/piezas.png 1744w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"><\/p>\n<figure><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/bluetab.net\/wp-content\/uploads\/2022\/03\/Isotipo-Bluetab-150x150.png\" alt=\"\" loading=\"lazy\"><\/figure>\n<h4>Bluetab<\/h4>\n<h5>\u00bfQuieres saber m\u00e1s de lo que ofrecemos y ver otros casos de \u00e9xito?<\/h5>\n<p><a href=\"\/\" role=\"button\"><br \/>\nDESCUBRE BLUETAB<br \/>\n<\/a><\/p>\n<p><b>SOLUCIONES, <\/b>SOMOS EXPERTOS<\/p>\n<p><a href=\"\/soluciones\/data-strategy\/\"><\/a><\/p>\n<p><a href=\"\/soluciones\/data-strategy\/\"><\/a><\/p>\n<p><a href=\"\/soluciones\/data-strategy\/\"><\/a><\/p>\n<p><a href=\"\/soluciones\/data-strategy\/\"><\/a><\/p>\n<p><a href=\"\/soluciones\/data-strategy\/\"><\/a><\/p>\n<p><a href=\"\/soluciones\/data-strategy\/\"><\/p>\n<h5>DATA STRATEGY<\/h5>\n<p><\/a><a href=\"\/soluciones\/data-strategy\/\"><\/a><a href=\"\/soluciones\/data-strategy\/\"><\/a><a href=\"\/soluciones\/data-strategy\/\"><\/a><a href=\"\/soluciones\/data-strategy\/\"><\/a><a href=\"\/soluciones\/data-strategy\/\">\t\t\t\t\t\t<\/a><br \/>\n<a href=\"\/soluciones\/data-fabric\/\"><\/a><\/p>\n<p><a href=\"\/soluciones\/data-fabric\/\"><\/a><\/p>\n<p><a href=\"\/soluciones\/data-fabric\/\"><\/a><\/p>\n<p><a href=\"\/soluciones\/data-fabric\/\"><\/a><\/p>\n<p><a href=\"\/soluciones\/data-fabric\/\"><\/a><\/p>\n<p><a href=\"\/soluciones\/data-fabric\/\"><\/p>\n<h5>DATA FABRIC<\/h5>\n<p><\/a><a href=\"\/soluciones\/data-fabric\/\"><\/a><a href=\"\/soluciones\/data-fabric\/\"><\/a><a href=\"\/soluciones\/data-fabric\/\"><\/a><a href=\"\/soluciones\/data-fabric\/\"><\/a><a href=\"\/soluciones\/data-fabric\/\">\t\t\t\t\t\t<\/a><br \/>\n<a href=\"\/soluciones\/augmented-analytics\/\"><\/a><\/p>\n<p><a href=\"\/soluciones\/augmented-analytics\/\"><\/a><\/p>\n<p><a href=\"\/soluciones\/augmented-analytics\/\"><\/a><\/p>\n<p><a href=\"\/soluciones\/augmented-analytics\/\"><\/a><\/p>\n<p><a href=\"\/soluciones\/augmented-analytics\/\"><\/a><\/p>\n<p><a href=\"\/soluciones\/augmented-analytics\/\"><\/p>\n<h5>AUGMENTED ANALYTICS<\/h5>\n<p><\/a><a href=\"\/soluciones\/augmented-analytics\/\"><\/a><a href=\"\/soluciones\/augmented-analytics\/\"><\/a><a href=\"\/soluciones\/augmented-analytics\/\"><\/a><a href=\"\/soluciones\/augmented-analytics\/\"><\/a><a href=\"\/soluciones\/augmented-analytics\/\">\t\t\t\t\t\t<\/a><\/p>\n<p>Te puede interesar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gobierno del dato en el sector de los servicios de Contact Center Bluetab Nuestro cliente es una compa\u00f1\u00eda multinacional de origen franc\u00e9s, con m\u00e1s de 44 a\u00f1os de experiencia en servicios de Contact Center&nbsp;(Business Process Outsourcing o BPO). Con m\u00e1s de 380 Mil empleados, y trabajando en m\u00e1s de 170 pa\u00edses y 260 lenguas. El [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20813,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[20,10],"tags":[],"class_list":["post-14219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casos-2","category-casos"],"acf":[],"_links":{"self":[{"href":"https:\/\/bluetab.co.uk\/en\/wp-json\/wp\/v2\/posts\/14219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluetab.co.uk\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bluetab.co.uk\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bluetab.co.uk\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bluetab.co.uk\/en\/wp-json\/wp\/v2\/comments?post=14219"}],"version-history":[{"count":0,"href":"https:\/\/bluetab.co.uk\/en\/wp-json\/wp\/v2\/posts\/14219\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluetab.co.uk\/en\/wp-json\/wp\/v2\/media\/20813"}],"wp:attachment":[{"href":"https:\/\/bluetab.co.uk\/en\/wp-json\/wp\/v2\/media?parent=14219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bluetab.co.uk\/en\/wp-json\/wp\/v2\/categories?post=14219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bluetab.co.uk\/en\/wp-json\/wp\/v2\/tags?post=14219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}